{"id":484,"count":54,"description":"","link":"https:\/\/esentyaestate.com\/no\/property_area\/pueblo\/","name":"Pueblo","slug":"pueblo","taxonomy":"property_area","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/esentyaestate.com\/no\/wp-json\/wp\/v2\/property_area\/484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentyaestate.com\/no\/wp-json\/wp\/v2\/property_area"}],"about":[{"href":"https:\/\/esentyaestate.com\/no\/wp-json\/wp\/v2\/taxonomies\/property_area"}],"wp:post_type":[{"href":"https:\/\/esentyaestate.com\/no\/wp-json\/wp\/v2\/estate_property?property_area=484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}