{"id":384,"count":1202,"description":"","link":"https:\/\/esentyaestate.com\/spa\/property_county_state\/costa-blanca-sur\/","name":"Costa Blanca Sur","slug":"costa-blanca-sur","taxonomy":"property_county_state","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/esentyaestate.com\/spa\/wp-json\/wp\/v2\/property_county_state\/384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esentyaestate.com\/spa\/wp-json\/wp\/v2\/property_county_state"}],"about":[{"href":"https:\/\/esentyaestate.com\/spa\/wp-json\/wp\/v2\/taxonomies\/property_county_state"}],"wp:post_type":[{"href":"https:\/\/esentyaestate.com\/spa\/wp-json\/wp\/v2\/estate_property?property_county_state=384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}